{"id":11866,"date":"2021-03-25T21:16:16","date_gmt":"2021-03-25T20:16:16","guid":{"rendered":"https:\/\/milagros.ch\/?p=11866"},"modified":"2021-08-04T15:00:03","modified_gmt":"2021-08-04T13:00:03","slug":"no-light-without-shadow","status":"publish","type":"post","link":"https:\/\/milagros.ch\/de\/no-light-without-shadow\/","title":{"rendered":"Wo Schatten ist, ist auch Licht"},"content":{"rendered":"<p class=\"has-text-align-center\"><em>Nach der Pechstr\u00e4hne der vorigen Woche sind wir motivationstechnisch nach wie vor noch nicht auf der H\u00f6he. Das Glasen will einfach nicht fertig werden und die Empfehlung eines Profis l\u00e4sst uns an unserem Vorgehen zweifeln. Zum Gl\u00fcck stand aber mein Geburtstag an, den wir ausgiebig feierten.<\/em><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"517\" src=\"https:\/\/milagros.ch\/wp-content\/uploads\/2021\/03\/title-shadow.jpg\" alt=\"\" class=\"wp-image-11884\" srcset=\"https:\/\/milagros.ch\/wp-content\/uploads\/2021\/03\/title-shadow.jpg 1024w, https:\/\/milagros.ch\/wp-content\/uploads\/2021\/03\/title-shadow-300x151.jpg 300w, https:\/\/milagros.ch\/wp-content\/uploads\/2021\/03\/title-shadow-768x388.jpg 768w, https:\/\/milagros.ch\/wp-content\/uploads\/2021\/03\/title-shadow-16x8.jpg 16w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-a-professional-opinion\">Die Profimeinung<\/h2>\n\n\n\n<p>Um f\u00fcr unsere H\u00fcllenrenovation einen Profi an der Hand zu haben, haben wir uns bei <a href=\"https:\/\/www.boatworkstoday.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">Andy von Boatworks Today<\/a> als Patreon registriert. So konnten wir ihm Fotos von Milagros schicken und seine Meinung zu unserem Vorgehen einholen. Wir hatten also damit begonnen, die tieferen Stellen am Rumpf mit Fiberglas zu f\u00fcllen, als wir von Andy die langersehnte Antwort erhielten. Und wir wollten sie nicht h\u00f6ren.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-the-recommendation\">Die Empfehlung<\/h2>\n\n\n\n<p>Er empfahl, die komplette H\u00fclle (\u00fcber und unter der Wasserlinie) zu spachteln und 1-2 Schichten sogenannter 1708 Biaxial-Glasfasermatte mit einer Dichte von 850g\/m2 (25 oz) zu verlegen. Damit w\u00fcrden alle delaminierten Stellen stabilisiert und das Osmose-Problem (h\u00f6chstwahrscheinlich) f\u00fcr immer gel\u00f6st. Eine 100% L\u00f6sung also, mit der wir quasi einen neuen Rumpf h\u00e4tten.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/milagros.ch\/wp-content\/uploads\/2021\/03\/fiberglassing-is-frustrating.jpg\" alt=\"\" class=\"wp-image-11870\" srcset=\"https:\/\/milagros.ch\/wp-content\/uploads\/2021\/03\/fiberglassing-is-frustrating.jpg 768w, https:\/\/milagros.ch\/wp-content\/uploads\/2021\/03\/fiberglassing-is-frustrating-225x300.jpg 225w, https:\/\/milagros.ch\/wp-content\/uploads\/2021\/03\/fiberglassing-is-frustrating-9x12.jpg 9w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><figcaption><em>Bootsarbeit ist manchmal frustrierend<\/em><\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-why-not\">Warum nicht?<\/h2>\n\n\n\n<p><strong>Es ist m\u00fchsam:<\/strong> Wer schon mal mit diesen Matten gearbeitet hat weiss, dass die Matte ist schon f\u00fcr kleine Reparaturen m\u00fchsam zu verarbeiten ist. Denn anders als Glasfaserstoff, muss die Matte vorab in Epoxy getr\u00e4nkt werden. Das macht sie schwer und unhandlich. Ganze Bahnen davon m\u00fcssen Horror sein. Zum Vergleich: Wir nutzen aktuell einfach gewobenen Glasfaserstoff mit einer Dichte von 250g\/m2 (7.5 oz), welcher sehr einfach zu verarbeiten ist.<\/p>\n\n\n\n<p><strong>Es ist eine Materialschlacht:<\/strong> Die Menge an ben\u00f6tigtem Material, vor allem Epoxy, ist enorm. Wir haben f\u00fcr die Blasenreparaturen schon beinahe eine Gallone Epoxy und 5m2 Stoff verarbeitet.<\/p>\n\n\n\n<p><strong>Es ist \u00fcbertrieben:<\/strong> Andy hat absolut recht \u2013 sein Vorgehen ist w\u00e4re optimal. Wird unser Schiff untergehen, wenn wir es nicht machen? Nein. Was ist das Schlimmste, was passieren kann, wenn wir Andys Rat nicht folgen? Der Anstrich kann versagen, und wir werden irgendwann in Zukunft wieder Osmosebehandlungen machen m\u00fcssen. Im schlimmsten Fall m\u00fcssen wir uns eingestehen, dass wir auf Andy h\u00e4tten h\u00f6ren sollen. Und vielleicht m\u00fcssen wir alles nochmals abschleifen und seinem Rat folgen. Oder auch nicht. Nichtdestotrotz wissen wir, dass er eigentlich Recht hat.<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-2 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/milagros.ch\/wp-content\/uploads\/2021\/03\/fiberglass-cloth.jpg\" alt=\"7.5 oz Glasfasergewebe, in passende St\u00fccke geschnitten\" data-id=\"11869\" data-full-url=\"https:\/\/milagros.ch\/wp-content\/uploads\/2021\/03\/fiberglass-cloth.jpg\" data-link=\"https:\/\/milagros.ch\/fiberglass-cloth\/\" class=\"wp-image-11869\" srcset=\"https:\/\/milagros.ch\/wp-content\/uploads\/2021\/03\/fiberglass-cloth.jpg 768w, https:\/\/milagros.ch\/wp-content\/uploads\/2021\/03\/fiberglass-cloth-225x300.jpg 225w, https:\/\/milagros.ch\/wp-content\/uploads\/2021\/03\/fiberglass-cloth-9x12.jpg 9w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><figcaption class=\"blocks-gallery-item__caption\"><em>Einige Lagen des 7.5 oz-Stoffes, bereit zum Auftragen<\/em><\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/milagros.ch\/wp-content\/uploads\/2021\/03\/too-many-blisters.jpg\" alt=\"Viele Blisters m\u00fcssen repariert werden\" data-id=\"11877\" data-full-url=\"https:\/\/milagros.ch\/wp-content\/uploads\/2021\/03\/too-many-blisters.jpg\" data-link=\"https:\/\/milagros.ch\/too-many-blisters\/\" class=\"wp-image-11877\" srcset=\"https:\/\/milagros.ch\/wp-content\/uploads\/2021\/03\/too-many-blisters.jpg 768w, https:\/\/milagros.ch\/wp-content\/uploads\/2021\/03\/too-many-blisters-225x300.jpg 225w, https:\/\/milagros.ch\/wp-content\/uploads\/2021\/03\/too-many-blisters-9x12.jpg 9w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><figcaption class=\"blocks-gallery-item__caption\"><em>Es sind sooooo viele!<\/em><\/figcaption><\/figure><\/li><\/ul><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-boat-pox\">Bootspocken<\/h2>\n\n\n\n<p>Die Seglercommunity hier ist wunderbar. Wir wurden aufgemuntert, konnten Andys Vorgehen besprechen und Vor- und Nachteile abw\u00e4gen. Schlussendlich haben wir uns dazu entschieden, bei unserem geplanten Vorgehen zu bleiben. Jedoch mit der Option, dass wir nach dem Spachteln am Unterwasserschiff 1 \u2013 2 Schichten Glasfaserstoff statt Matte verlegen, je nach dem wie das Resultat aussieht. Beim Bl\u00e4ttern in einem unserer B\u00fccher habe ich entdeckt, dass der Zustand unserer H\u00fclle einen eigenen Namen hat: Bootspocken.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-a-systemic-problem\">Ein systemisches Problem<\/h2>\n\n\n\n<p>Die Osmoseblasen entstehen zwischen dem Gelcoat und der ersten Fiberglasschicht, wenn der Gelcoat seine Schutzfunktion nicht mehr wahrnimmt. Bei den Bootspocken treten die Blasen nicht vereinzelt auf, sondern \u00fcber das komplette Unterwasserschiff verteilt und stellen ein systemisches Problem dar. Dann muss der komplette Gelcoat entfernt und der Anstrich neu aufgebaut werden.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-common-practice\">G\u00e4ngige Praxis<\/h2>\n\n\n\n<p>Bei uns kommt noch dazu, dass viele Blasen tiefer gehen und sich zwischen der ersten und zweiten Fiberglasschicht befinden. Das Problem entsteht \u00fcblicherweise schon beim Schiffsbau, wenn damit begonnen wird, das Schiff von aussen nach innen in der Verschalung aufzubauen. Es ist leider g\u00e4ngige Praxis, auf den noch feuchten Gelcoat die erste Schicht Fiberglas zu legen und dann einen Tag zu warten, bis die zweite Schicht aufgetragen wird. Das f\u00fchrt dazu, dass die Verbindung zwischen den beiden Schichten nicht so gut und deshalb anf\u00e4llig f\u00fcr Blasen ist. Die vorgeschlagene L\u00f6sung ist, die korrumpierte Schicht zu entfernen und durch eine Lage 350g\/m2 (10 oz) Glasfaserstoff zu ersetzen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-no-end-in-sight\">Kein Ende in Sicht<\/h2>\n\n\n\n<p>Wir bleiben aber <a href=\"https:\/\/milagros.ch\/de\/vom-pech-verfolgt\/#h-we-test-the-next-steps\">dabei<\/a>: keine zus\u00e4tzliche Schicht und wir glasen fr\u00f6hlich, und manchmal weniger fr\u00f6hlich, weiter. Eine so grosse Fl\u00e4che zu bearbeiten, ist herausfordernd und teilweise fast \u00fcberfordernd. Vor allem weil wir zeitweise an unserem Entscheid zweifelten und nicht sicher waren ob wir das richtige tun. Um die \u00dcbersicht nicht zu verlieren, haben wir ein Gitternetz auf die H\u00fclle gemalt \u2013 so konnten wir uns Quadrat f\u00fcr Quadrat vorarbeiten, an etwas entlanghangeln und kleine Erfolge feiern. Der Frust bei dieser Arbeit wurde noch dadurch verst\u00e4rkt, dass gleich drei Boote einwasserten und ein weiteres so gut wie parat zum Einwassern war. Wir wollten einerseits auch los und andererseits \"verloren\" wir tolle Leute hier auf dem Yard.<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-2 is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/milagros.ch\/wp-content\/uploads\/2021\/03\/milagros-with-a-grid.jpg\" alt=\"Am fiberglasen\" data-id=\"11873\" data-full-url=\"https:\/\/milagros.ch\/wp-content\/uploads\/2021\/03\/milagros-with-a-grid.jpg\" data-link=\"https:\/\/milagros.ch\/milagros-with-a-grid\/\" class=\"wp-image-11873\" srcset=\"https:\/\/milagros.ch\/wp-content\/uploads\/2021\/03\/milagros-with-a-grid.jpg 768w, https:\/\/milagros.ch\/wp-content\/uploads\/2021\/03\/milagros-with-a-grid-225x300.jpg 225w, https:\/\/milagros.ch\/wp-content\/uploads\/2021\/03\/milagros-with-a-grid-9x12.jpg 9w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><figcaption class=\"blocks-gallery-item__caption\"><em>Unser Fortschritt<\/em><\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/milagros.ch\/wp-content\/uploads\/2021\/03\/grid-on-milagros.jpg\" alt=\"Ein Raster auf dem Rumpf hilft uns, uns zu orientieren\" data-id=\"11871\" data-full-url=\"https:\/\/milagros.ch\/wp-content\/uploads\/2021\/03\/grid-on-milagros.jpg\" data-link=\"https:\/\/milagros.ch\/grid-on-milagros\/\" class=\"wp-image-11871\" srcset=\"https:\/\/milagros.ch\/wp-content\/uploads\/2021\/03\/grid-on-milagros.jpg 1024w, https:\/\/milagros.ch\/wp-content\/uploads\/2021\/03\/grid-on-milagros-300x225.jpg 300w, https:\/\/milagros.ch\/wp-content\/uploads\/2021\/03\/grid-on-milagros-768x576.jpg 768w, https:\/\/milagros.ch\/wp-content\/uploads\/2021\/03\/grid-on-milagros-16x12.jpg 16w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"blocks-gallery-item__caption\"><em>Milagros mit ihrem neuen gr\u00fcnen Gitter<\/em><\/figcaption><\/figure><\/li><\/ul><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-my-birthday\">Mein Geburtstag<\/h2>\n\n\n\n<p>Ich war ziemlich froh, dass in dieser Woche mein 27. Geburtstag zum sechsten Mal anstand. Schon l\u00e4nger hegten wir den Plan, selbst die richtig nervigen Strandbuggies zu mieten, die uns schon seit Monaten mit ihrem L\u00e4rm nervten. Als wir die Idee mit ein paar anderen Bewohnern des Boatyards teilten, waren <a href=\"https:\/\/www.instagram.com\/theyvegonetoplaid\/\" target=\"_blank\" rel=\"noreferrer noopener\">SV Cavu<\/a>, <a href=\"https:\/\/www.instagram.com\/sailingalegria\" target=\"_blank\" rel=\"noreferrer noopener\">SV Alegr\u00eda<\/a> und <a href=\"https:\/\/www.instagram.com\/svliquid\/\" target=\"_blank\" rel=\"noreferrer noopener\">SV Liquid<\/a> sofort mit dabei. Gemeinsam mit Mike und Katie von SV Alegr\u00eda und Betty, ihrem Auto, und Rosco, ihrem Hund, checkten wir vorab die Preise entlang der Strasse, um den besten Deal zu finden. Der Razor (der coolste), den wir im Visier hatten, kostete jedoch satte 250$ pro Stunde. Nein danke. Wir entschieden uns f\u00fcr die etwas weniger coolen Rhinos, quasi Golfcarts mit Vierradantrieb. 40$ pro Stunde und vier Sitze schien uns passend.<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-2 is-cropped wp-block-gallery-3 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/milagros.ch\/wp-content\/uploads\/2021\/03\/betty-got-stuck.jpg\" alt=\"\" data-id=\"11880\" data-full-url=\"https:\/\/milagros.ch\/wp-content\/uploads\/2021\/03\/betty-got-stuck.jpg\" data-link=\"https:\/\/milagros.ch\/betty-got-stuck\/\" class=\"wp-image-11880\" srcset=\"https:\/\/milagros.ch\/wp-content\/uploads\/2021\/03\/betty-got-stuck.jpg 1024w, https:\/\/milagros.ch\/wp-content\/uploads\/2021\/03\/betty-got-stuck-300x225.jpg 300w, https:\/\/milagros.ch\/wp-content\/uploads\/2021\/03\/betty-got-stuck-768x576.jpg 768w, https:\/\/milagros.ch\/wp-content\/uploads\/2021\/03\/betty-got-stuck-16x12.jpg 16w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"blocks-gallery-item__caption\"><em>Betty blieb stecken<\/em><\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/milagros.ch\/wp-content\/uploads\/2021\/03\/deep-sand.jpg\" alt=\"\" data-id=\"11883\" data-full-url=\"https:\/\/milagros.ch\/wp-content\/uploads\/2021\/03\/deep-sand.jpg\" data-link=\"https:\/\/milagros.ch\/deep-sand\/\" class=\"wp-image-11883\" srcset=\"https:\/\/milagros.ch\/wp-content\/uploads\/2021\/03\/deep-sand.jpg 1024w, https:\/\/milagros.ch\/wp-content\/uploads\/2021\/03\/deep-sand-300x225.jpg 300w, https:\/\/milagros.ch\/wp-content\/uploads\/2021\/03\/deep-sand-768x576.jpg 768w, https:\/\/milagros.ch\/wp-content\/uploads\/2021\/03\/deep-sand-16x12.jpg 16w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"blocks-gallery-item__caption\"><em>Im Sand eingesunken<\/em><\/figcaption><\/figure><\/li><\/ul><figcaption class=\"blocks-gallery-caption\"><em>Zwei Einheimische halfen uns aus der Misere<\/em><\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-the-first-day-off\">Der erste freie Tag<\/h2>\n\n\n\n<p>Ein komplett freier Tag ohne Arbeit am Boot \u2013 der erste seit beinahe 2 Monaten \u2013 hatten wir und auch andere n\u00f6tig. Wir trafen uns also morgens um 10 alle bei Milagros f\u00fcr Kaffee und <s>Kuchen<\/s> Bier. Ich habe mich sehr \u00fcber die vielen Segler gefreut, die gekommen sind, und mit mir angestossen haben. Voller Vorfreude zogen wir danach los und mieteten zwei Rhinos \u2013 einen in pink und einen in schnellem rot. Cavu Dave und Alegr\u00eda Mike \u00fcbernahmen als erstes das Steuer. Schon als wir kurz zum Boatyard fuhren, um Musikboxen zu holen, wusste ich: das hat sich gelohnt! Die \u00fcbermotorisierten und topgefederten Fahrzeuge machten L\u00e4rm und Spass.<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-2 is-cropped wp-block-gallery-4 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/milagros.ch\/wp-content\/uploads\/2021\/03\/birthday-drink.jpg\" alt=\"\" data-id=\"11881\" data-full-url=\"https:\/\/milagros.ch\/wp-content\/uploads\/2021\/03\/birthday-drink.jpg\" data-link=\"https:\/\/milagros.ch\/birthday-drink\/\" class=\"wp-image-11881\" srcset=\"https:\/\/milagros.ch\/wp-content\/uploads\/2021\/03\/birthday-drink.jpg 768w, https:\/\/milagros.ch\/wp-content\/uploads\/2021\/03\/birthday-drink-225x300.jpg 225w, https:\/\/milagros.ch\/wp-content\/uploads\/2021\/03\/birthday-drink-9x12.jpg 9w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><figcaption class=\"blocks-gallery-item__caption\"><em>Kaffee mit Schuss<\/em><\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/milagros.ch\/wp-content\/uploads\/2021\/03\/happy-birthday-pati.jpg\" alt=\"\" data-id=\"11872\" data-full-url=\"https:\/\/milagros.ch\/wp-content\/uploads\/2021\/03\/happy-birthday-pati.jpg\" data-link=\"https:\/\/milagros.ch\/happy-birthday-pati\/\" class=\"wp-image-11872\" srcset=\"https:\/\/milagros.ch\/wp-content\/uploads\/2021\/03\/happy-birthday-pati.jpg 1024w, https:\/\/milagros.ch\/wp-content\/uploads\/2021\/03\/happy-birthday-pati-300x225.jpg 300w, https:\/\/milagros.ch\/wp-content\/uploads\/2021\/03\/happy-birthday-pati-768x576.jpg 768w, https:\/\/milagros.ch\/wp-content\/uploads\/2021\/03\/happy-birthday-pati-16x12.jpg 16w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"blocks-gallery-item__caption\"><em>Um den Rhino zu fahren, schenkten mir Dave und Mike diese wirklich sch\u00f6ne (nicht) Sonnenbrille<\/em><\/figcaption><\/figure><\/li><\/ul><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-a-shortcut\">Eine Abk\u00fcrzung<\/h2>\n\n\n\n<p>Auf dem Weg zu den D\u00fcnen von La Choya verliessen wir bei der ersten Gelegenheit die befestigte Strasse und nahmen eine Abk\u00fcrzung durch den Sand. Diese Dinger sind nicht f\u00fcr die Strasse gemacht, ihr nat\u00fcrliches Habitat ist der Sand. So testeten wir gleich mal die Federung, den Einschlag und den 4x4. Die Mitfahrer auf dem R\u00fccksitz und das Bier wurden kr\u00e4ftig durchgesch\u00fcttelt wie auf einer Achterbahn. Das war erst der Vorgeschmack und wir wollten mehr.<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-2 is-cropped wp-block-gallery-5 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/milagros.ch\/wp-content\/uploads\/2021\/03\/rhino-ride.jpg\" alt=\"Rhinos in Puerto Pe\u00f1asco\" data-id=\"11876\" data-full-url=\"https:\/\/milagros.ch\/wp-content\/uploads\/2021\/03\/rhino-ride.jpg\" data-link=\"https:\/\/milagros.ch\/rhino-ride\/\" class=\"wp-image-11876\" srcset=\"https:\/\/milagros.ch\/wp-content\/uploads\/2021\/03\/rhino-ride.jpg 768w, https:\/\/milagros.ch\/wp-content\/uploads\/2021\/03\/rhino-ride-225x300.jpg 225w, https:\/\/milagros.ch\/wp-content\/uploads\/2021\/03\/rhino-ride-9x12.jpg 9w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><figcaption class=\"blocks-gallery-item__caption\"><em>Marla am Steuer<\/em><\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/milagros.ch\/wp-content\/uploads\/2021\/03\/crazy-rhino-ride.jpg\" alt=\"ATV Spass in Puerto Pe\u00f1asco\" data-id=\"11882\" data-full-url=\"https:\/\/milagros.ch\/wp-content\/uploads\/2021\/03\/crazy-rhino-ride.jpg\" data-link=\"https:\/\/milagros.ch\/crazy-rhino-ride\/\" class=\"wp-image-11882\" srcset=\"https:\/\/milagros.ch\/wp-content\/uploads\/2021\/03\/crazy-rhino-ride.jpg 1024w, https:\/\/milagros.ch\/wp-content\/uploads\/2021\/03\/crazy-rhino-ride-300x225.jpg 300w, https:\/\/milagros.ch\/wp-content\/uploads\/2021\/03\/crazy-rhino-ride-768x576.jpg 768w, https:\/\/milagros.ch\/wp-content\/uploads\/2021\/03\/crazy-rhino-ride-16x12.jpg 16w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"blocks-gallery-item__caption\"><em>Rhinos machen Spass!<\/em><\/figcaption><\/figure><\/li><\/ul><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-la-choya\">La Choya<\/h2>\n\n\n\n<p>Kurz vor La Choya konnte man erneut von der Strasse abfahren und durch die W\u00fcste heizen. Eine Buckelpiste soweit das Auge reichte. Da Donnerstag war, hatte es praktisch keine anderen Leute. Abwechselnd trieben wir unsere Gef\u00e4hrte ans Limit, und fuhren mit den anderen um die Wette. Marla von SV Cavu schaffte es sogar, die Maximalgeschwindigkeit von 60km\/h zu erreichen. Ein Bier zu trinken auf dem R\u00fccksitz war ein Ding der Unm\u00f6glichkeit. Der H\u00f6hepunkt war, als wir <a href=\"https:\/\/goo.gl\/maps\/Qo3gd43LghzuRe1A8\" target=\"_blank\" rel=\"noreferrer noopener\">den Berg von La Choya (San Juan Hill)<\/a> erklommen und oben mit einer tollen Aussicht belohnt wurden. Mit Tequila stiessen wir auf meinen Geburtstag an. Was f\u00fcr ein Spass!<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/milagros.ch\/wp-content\/uploads\/2021\/03\/atop-la-choya.jpg\" alt=\"Die Aussicht von La Choya\" class=\"wp-image-11879\" srcset=\"https:\/\/milagros.ch\/wp-content\/uploads\/2021\/03\/atop-la-choya.jpg 1024w, https:\/\/milagros.ch\/wp-content\/uploads\/2021\/03\/atop-la-choya-300x225.jpg 300w, https:\/\/milagros.ch\/wp-content\/uploads\/2021\/03\/atop-la-choya-768x576.jpg 768w, https:\/\/milagros.ch\/wp-content\/uploads\/2021\/03\/atop-la-choya-16x12.jpg 16w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption><em>Die Rhino-Crew mit einer sch\u00f6nen Aussicht im Hintergrund (Bild von Alegr\u00eda Mike)<\/em><\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-exhausted-and-happy\">Ersch\u00f6pft und gl\u00fccklich<\/h2>\n\n\n\n<p>Nach 2 Stunden brachten wir die Rhinos ersch\u00f6pft vom Ger\u00fcttele und Gesch\u00fcttele wieder zur\u00fcck. Vielleicht haben wir es etwas \u00fcbertrieben, denn beide Buggies machten komische Ger\u00e4usche, die sie zuvor nicht gemacht hatten. Cavu Dave hat es bezeichnend ausgedr\u00fcckt: \"Es f\u00fchlt sich an, als ob ich einen Autounfalll hatte\". Das Fazit war auf jeden Fall: es hat viel mehr Spass gemacht, als erwartet. Und wir haben nun auch ein bisschen mehr Verst\u00e4ndnis f\u00fcr all die Touris, die damit um den Boatyard heizen. Aber nur ein bisschen, denn wie gesagt: diese Dinger m\u00fcssen in den Sand, und nicht auf die Strasse.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"790\" src=\"https:\/\/milagros.ch\/wp-content\/uploads\/2021\/03\/rhino-fun-1024x790.jpg\" alt=\"ATV Spass in Puerto Pe\u00f1asco\" class=\"wp-image-11875\" srcset=\"\" sizes=\"(max-width: 1024px) 100vw, 1024px\" data-srcset=\"\" \/><figcaption><em>Foto von Liquid Marc<\/em><\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-the-fun-continues\">Der Spass geht weiter<\/h2>\n\n\n\n<p>P\u00fcnktlich zur Einwasserung von SV Catspaw waren wir wieder auf dem Yard. Eine Einwasserung ist immer ein grossens Event, da es (\u00fcblicherweise) das Ende der Arbeit und den Anfang des Vergn\u00fcgens bedeutet. Im Anschluss wurde ich mit einer Oreo Eistorte von DairyQueen \u00fcberrascht \u2013 sogar mit Kerzen, die ich aber Corona-technisch nicht auspustete. Wir liessen den Abend mit Fischtacos und Bier bei SV Dogfish ausklingen. Was f\u00fcr ein Tag!<\/p>\n\n\n\n<p>Willst du Patricia zum Geburtstag gratulieren? Das kannst du zum Beispiel tun, indem du auf den Button weiter unten klickst (du brauchst nicht mal einen Account!). Du kannst uns auch auf&nbsp;<a href=\"https:\/\/www.patreon.com\/milagros_sailing\" target=\"_blank\" rel=\"noreferrer noopener\">Patreon<\/a>.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link\" href=\"https:\/\/www.buymeacoffee.com\/milagrossailing\" target=\"_blank\" rel=\"noreferrer noopener\">\ud83c\udf81 Schenke Patricia etwas zum Geburtstag!<\/a><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Die Arbeit scheint endlos und eine Empfehlung eines Profis l\u00e4sst uns an unserer Vorgehensweise zweifeln. Zeit, einen Tag frei zu nehmen und meinen Geburtstag zu feiern.<\/p>","protected":false},"author":3,"featured_media":11884,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"cybocfi_hide_featured_image":"yes","footnotes":""},"categories":[30,26,25,21,39],"tags":[57,88,56],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.0 (Yoast SEO v23.5) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>No Light without Shadow &#8226; Milagros &#8226; Sailing Blog 2021<\/title>\n<meta name=\"description\" content=\"The work seems endless and a recommendation of a professional makes us doubt our approach. Time to take a day off and celebrate my birthday.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/milagros.ch\/de\/kein-licht-ohne-schatten\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Where there is Light, there is Shadow\" \/>\n<meta property=\"og:description\" content=\"The work seems endless and a recommendation of a professional makes us doubt our approach. Time to take a day off and celebrate my birthday.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/milagros.ch\/de\/kein-licht-ohne-schatten\/\" \/>\n<meta property=\"og:site_name\" content=\"Milagros\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/milagros.sailing\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-25T20:16:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-04T13:00:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/milagros.ch\/wp-content\/uploads\/2021\/03\/title-shadow.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"517\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Patricia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschrieben von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Patricia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/milagros.ch\/de\/kein-licht-ohne-schatten\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/milagros.ch\/de\/kein-licht-ohne-schatten\/\"},\"author\":{\"name\":\"Patricia\",\"@id\":\"https:\/\/milagros.ch\/#\/schema\/person\/bf6747fcb66e878e86c2169f4bf869af\"},\"headline\":\"Where there is Light, there is Shadow\",\"datePublished\":\"2021-03-25T20:16:16+00:00\",\"dateModified\":\"2021-08-04T13:00:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/milagros.ch\/de\/kein-licht-ohne-schatten\/\"},\"wordCount\":1466,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\/\/milagros.ch\/#organization\"},\"image\":{\"@id\":\"https:\/\/milagros.ch\/de\/kein-licht-ohne-schatten\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/milagros.ch\/wp-content\/uploads\/2021\/03\/title-shadow.jpg\",\"keywords\":[\"Cruising Community\",\"Fibreglass\",\"Osmosis Treatment\"],\"articleSection\":[\"Boat Refit\",\"Friends &amp; Family\",\"Life happens\",\"Mexico\",\"Puerto Pe\u00f1asco\"],\"inLanguage\":\"de-CH\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/milagros.ch\/de\/kein-licht-ohne-schatten\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/milagros.ch\/de\/kein-licht-ohne-schatten\/\",\"url\":\"https:\/\/milagros.ch\/de\/kein-licht-ohne-schatten\/\",\"name\":\"No Light without Shadow &#8226; Milagros &#8226; Sailing Blog 2021\",\"isPartOf\":{\"@id\":\"https:\/\/milagros.ch\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/milagros.ch\/de\/kein-licht-ohne-schatten\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/milagros.ch\/de\/kein-licht-ohne-schatten\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/milagros.ch\/wp-content\/uploads\/2021\/03\/title-shadow.jpg\",\"datePublished\":\"2021-03-25T20:16:16+00:00\",\"dateModified\":\"2021-08-04T13:00:03+00:00\",\"description\":\"The work seems endless and a recommendation of a professional makes us doubt our approach. Time to take a day off and celebrate my birthday.\",\"breadcrumb\":{\"@id\":\"https:\/\/milagros.ch\/de\/kein-licht-ohne-schatten\/#breadcrumb\"},\"inLanguage\":\"de-CH\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/milagros.ch\/de\/kein-licht-ohne-schatten\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/milagros.ch\/de\/kein-licht-ohne-schatten\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/milagros.ch\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Where there is Light, there is Shadow\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/milagros.ch\/#website\",\"url\":\"https:\/\/milagros.ch\/\",\"name\":\"Milagros\",\"description\":\"Nice to meet you!\",\"publisher\":{\"@id\":\"https:\/\/milagros.ch\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/milagros.ch\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-CH\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/milagros.ch\/#organization\",\"name\":\"Milagros Sailing\",\"url\":\"https:\/\/milagros.ch\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-CH\",\"@id\":\"https:\/\/milagros.ch\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/milagros.ch\/wp-content\/uploads\/2021\/02\/Milagros_black.jpg\",\"contentUrl\":\"https:\/\/milagros.ch\/wp-content\/uploads\/2021\/02\/Milagros_black.jpg\",\"width\":512,\"height\":512,\"caption\":\"Milagros Sailing\"},\"image\":{\"@id\":\"https:\/\/milagros.ch\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/milagros.sailing\",\"https:\/\/www.instagram.com\/milagros_sailing\/\",\"https:\/\/www.linkedin.com\/company\/milagros-sailing\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/milagros.ch\/#\/schema\/person\/bf6747fcb66e878e86c2169f4bf869af\",\"name\":\"Patricia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-CH\",\"@id\":\"https:\/\/milagros.ch\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8642c08f46e95a6c774a41afa7f1b2c1?s=96&d=retro&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8642c08f46e95a6c774a41afa7f1b2c1?s=96&d=retro&r=g\",\"caption\":\"Patricia\"},\"url\":\"https:\/\/milagros.ch\/de\/author\/patriciabueeler\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"No Light without Shadow &#8226; Milagros &#8226; Sailing Blog 2021","description":"Die Arbeit scheint endlos und eine Empfehlung eines Profis l\u00e4sst uns an unserer Vorgehensweise zweifeln. Zeit, einen Tag frei zu nehmen und meinen Geburtstag zu feiern.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/milagros.ch\/de\/kein-licht-ohne-schatten\/","og_locale":"de_DE","og_type":"article","og_title":"Where there is Light, there is Shadow","og_description":"The work seems endless and a recommendation of a professional makes us doubt our approach. Time to take a day off and celebrate my birthday.","og_url":"https:\/\/milagros.ch\/de\/kein-licht-ohne-schatten\/","og_site_name":"Milagros","article_publisher":"https:\/\/www.facebook.com\/milagros.sailing","article_published_time":"2021-03-25T20:16:16+00:00","article_modified_time":"2021-08-04T13:00:03+00:00","og_image":[{"width":1024,"height":517,"url":"https:\/\/milagros.ch\/wp-content\/uploads\/2021\/03\/title-shadow.jpg","type":"image\/jpeg"}],"author":"Patricia","twitter_card":"summary_large_image","twitter_misc":{"Geschrieben von":"Patricia","Gesch\u00e4tzte Lesezeit":"10 Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/milagros.ch\/de\/kein-licht-ohne-schatten\/#article","isPartOf":{"@id":"https:\/\/milagros.ch\/de\/kein-licht-ohne-schatten\/"},"author":{"name":"Patricia","@id":"https:\/\/milagros.ch\/#\/schema\/person\/bf6747fcb66e878e86c2169f4bf869af"},"headline":"Where there is Light, there is Shadow","datePublished":"2021-03-25T20:16:16+00:00","dateModified":"2021-08-04T13:00:03+00:00","mainEntityOfPage":{"@id":"https:\/\/milagros.ch\/de\/kein-licht-ohne-schatten\/"},"wordCount":1466,"commentCount":2,"publisher":{"@id":"https:\/\/milagros.ch\/#organization"},"image":{"@id":"https:\/\/milagros.ch\/de\/kein-licht-ohne-schatten\/#primaryimage"},"thumbnailUrl":"https:\/\/milagros.ch\/wp-content\/uploads\/2021\/03\/title-shadow.jpg","keywords":["Cruising Community","Fibreglass","Osmosis Treatment"],"articleSection":["Boat Refit","Friends &amp; Family","Life happens","Mexico","Puerto Pe\u00f1asco"],"inLanguage":"de-CH","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/milagros.ch\/de\/kein-licht-ohne-schatten\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/milagros.ch\/de\/kein-licht-ohne-schatten\/","url":"https:\/\/milagros.ch\/de\/kein-licht-ohne-schatten\/","name":"No Light without Shadow &#8226; Milagros &#8226; Sailing Blog 2021","isPartOf":{"@id":"https:\/\/milagros.ch\/#website"},"primaryImageOfPage":{"@id":"https:\/\/milagros.ch\/de\/kein-licht-ohne-schatten\/#primaryimage"},"image":{"@id":"https:\/\/milagros.ch\/de\/kein-licht-ohne-schatten\/#primaryimage"},"thumbnailUrl":"https:\/\/milagros.ch\/wp-content\/uploads\/2021\/03\/title-shadow.jpg","datePublished":"2021-03-25T20:16:16+00:00","dateModified":"2021-08-04T13:00:03+00:00","description":"Die Arbeit scheint endlos und eine Empfehlung eines Profis l\u00e4sst uns an unserer Vorgehensweise zweifeln. Zeit, einen Tag frei zu nehmen und meinen Geburtstag zu feiern.","breadcrumb":{"@id":"https:\/\/milagros.ch\/de\/kein-licht-ohne-schatten\/#breadcrumb"},"inLanguage":"de-CH","potentialAction":[{"@type":"ReadAction","target":["https:\/\/milagros.ch\/de\/kein-licht-ohne-schatten\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/milagros.ch\/de\/kein-licht-ohne-schatten\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/milagros.ch\/"},{"@type":"ListItem","position":2,"name":"Where there is Light, there is Shadow"}]},{"@type":"WebSite","@id":"https:\/\/milagros.ch\/#website","url":"https:\/\/milagros.ch\/","name":"Milagros","description":"Sch\u00f6n dich kennen zu lernen!","publisher":{"@id":"https:\/\/milagros.ch\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/milagros.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-CH"},{"@type":"Organization","@id":"https:\/\/milagros.ch\/#organization","name":"Milagros Sailing","url":"https:\/\/milagros.ch\/","logo":{"@type":"ImageObject","inLanguage":"de-CH","@id":"https:\/\/milagros.ch\/#\/schema\/logo\/image\/","url":"https:\/\/milagros.ch\/wp-content\/uploads\/2021\/02\/Milagros_black.jpg","contentUrl":"https:\/\/milagros.ch\/wp-content\/uploads\/2021\/02\/Milagros_black.jpg","width":512,"height":512,"caption":"Milagros Sailing"},"image":{"@id":"https:\/\/milagros.ch\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/milagros.sailing","https:\/\/www.instagram.com\/milagros_sailing\/","https:\/\/www.linkedin.com\/company\/milagros-sailing"]},{"@type":"Person","@id":"https:\/\/milagros.ch\/#\/schema\/person\/bf6747fcb66e878e86c2169f4bf869af","name":"Patricia","image":{"@type":"ImageObject","inLanguage":"de-CH","@id":"https:\/\/milagros.ch\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/8642c08f46e95a6c774a41afa7f1b2c1?s=96&d=retro&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8642c08f46e95a6c774a41afa7f1b2c1?s=96&d=retro&r=g","caption":"Patricia"},"url":"https:\/\/milagros.ch\/de\/author\/patriciabueeler\/"}]}},"_links":{"self":[{"href":"https:\/\/milagros.ch\/de\/wp-json\/wp\/v2\/posts\/11866"}],"collection":[{"href":"https:\/\/milagros.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/milagros.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/milagros.ch\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/milagros.ch\/de\/wp-json\/wp\/v2\/comments?post=11866"}],"version-history":[{"count":17,"href":"https:\/\/milagros.ch\/de\/wp-json\/wp\/v2\/posts\/11866\/revisions"}],"predecessor-version":[{"id":12079,"href":"https:\/\/milagros.ch\/de\/wp-json\/wp\/v2\/posts\/11866\/revisions\/12079"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/milagros.ch\/de\/wp-json\/wp\/v2\/media\/11884"}],"wp:attachment":[{"href":"https:\/\/milagros.ch\/de\/wp-json\/wp\/v2\/media?parent=11866"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/milagros.ch\/de\/wp-json\/wp\/v2\/categories?post=11866"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/milagros.ch\/de\/wp-json\/wp\/v2\/tags?post=11866"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}