{"id":11061,"date":"2021-01-07T07:30:47","date_gmt":"2021-01-07T06:30:47","guid":{"rendered":"https:\/\/milagros.ch\/?p=11061"},"modified":"2021-08-04T11:49:18","modified_gmt":"2021-08-04T09:49:18","slug":"10-faq","status":"publish","type":"post","link":"https:\/\/milagros.ch\/de\/10-faq\/","title":{"rendered":"10 Fragen zu unserem Abenteuer"},"content":{"rendered":"<p class=\"has-text-align-center\"><em>Wenn wir von unserem Vorhaben erz\u00e4hlen, gibt es Fragen, die es immer und immer wieder zu beantworten gilt. Wir haben die 10 h\u00e4ufigsten Fragen beantwortet.<\/em><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"395\" src=\"https:\/\/milagros.ch\/wp-content\/uploads\/2021\/01\/title-10-faq_narrow-1024x395.jpg\" alt=\"\" class=\"wp-image-11065\" srcset=\"\" sizes=\"(max-width: 1024px) 100vw, 1024px\" data-srcset=\"\" \/><\/figure>\n\n\n\n<h2 class=\"has-text-align-center wp-block-heading\" id=\"h-prologue\">Prolog<\/h2>\n\n\n\n<p>Was im 2018 als Schnapsidee begann, wird f\u00fcr <a href=\"https:\/\/milagros.ch\/de\/die-crew\/\" target=\"_blank\" rel=\"noreferrer noopener\"><span style=\"color:#0693e3\" class=\"tadv-color\">David und mich<\/span><\/a> jetzt \u2013 mit fast einem Jahr Versp\u00e4tung wegen Corona \u2013 zur Wirklichkeit: Wir starten unser bisher gr\u00f6sstes Abenteuer, gemeinsam mit <a href=\"https:\/\/milagros.ch\/de\/our-kelly-peterson-44\/\" target=\"_blank\" rel=\"noreferrer noopener\"><span style=\"color:#0693e3\" class=\"tadv-color\">unserem Segelschiff Milagros<\/span><\/a> und mit Anila und Crew.<\/p>\n\n\n\n<p>Milagros (auf Deutsch \"Wunder\") ist eine 44 Fuss (ca. 13m) lange Kelly Peterson Blauwasseryacht, die <a href=\"https:\/\/milagros.ch\/de\/wir-sind-bootsbesitzer\/\" target=\"_blank\" rel=\"noreferrer noopener\"><span style=\"color:#0693e3\" class=\"tadv-color\">wir im August 2019 an der Pazifikk\u00fcste in Mexiko in der N\u00e4he von Tijuana erstanden haben<\/span><\/a>. Anila ist das Schiff meiner Schwester und ihrem Partner (unserem Segellehrer).<\/p>\n\n\n\n<h2 class=\"has-text-align-center wp-block-heading\" id=\"h-the-10-most-frequently-asked-questions\">Die 10 h\u00e4ufigsten Fragen<\/h2>\n\n\n\n<p>Nachfolgend die aus unserer Erfahrung der letzten 12 Monate am h\u00e4ufigsten gestellten Fragen rund um unser Abenteuer.<\/p>\n\n\n\n<h3 class=\"has-text-align-center wp-block-heading\" id=\"h-1-how-long-do-you-want-to-travel\">1. Wie lange wollt ihr denn wegbleiben?<\/h3>\n\n\n\n<p>Ich z\u00e4hle dann an meiner Hand, die die Zahl Nummer 3 zeigt, das Folgende ab: Bis wir entweder keine Lust, kein Geld oder kein Schiff mehr haben. Also, auf unbegrenzte Zeit.<\/p>\n\n\n\n<h3 class=\"has-text-align-center wp-block-heading\" id=\"h-2-what-does-a-sailboat-actually-cost\">2. Darf ich fragen, was so ein Schiff \u00fcberhaupt kostet?<\/h3>\n\n\n\n<p>Klar, wir haben 71'000$ bezahlt. Das ist n\u00e4mlich gar nicht so viel, wenn man bedenkt, dass wir damit quasi ein mobiles Eigenheim besitzen.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/milagros.ch\/wp-content\/uploads\/2021\/01\/Milagros-1024x768.jpg\" alt=\"Milagros&#039; Unterwasserschiff braucht etwas Aufmerksamkeit\" class=\"wp-image-11071\" srcset=\"\" sizes=\"(max-width: 1024px) 100vw, 1024px\" data-srcset=\"\" \/><figcaption>Wenn man ein Segelschiff kauft, h\u00f6rt die Arbeit niemals auf<\/figcaption><\/figure>\n\n\n\n<h3 class=\"has-text-align-center wp-block-heading\" id=\"h-3-what-does-such-an-undertaking-cost\">3. Und was kostet denn ein solches Abenteuer?<\/h3>\n\n\n\n<p>Wir haben verschiedene B\u00fccher und Blogs gelesen und draus abgeleitet, dass wir mit 1'000 CHF pro Person pro Monat auf der sicheren Seite sind. Das heisst, wir rechnen mit etwa 24'000 CHF pro Jahr f\u00fcr uns beide. Man sagt, dass etwa 10% des Schiffwertes, also hier ca. 7'000 \u2013 10'000 CHF in Unterhalt investiert werden muss. Aufgerundet sind das durchschnittlich 1'000 CHF pro Monat. Dann bleiben noch etwa 1'000 CHF pro Monat \u00fcbrig f\u00fcr alles andere.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/milagros.ch\/wp-content\/uploads\/2021\/01\/dave-in-the-shop-1024x768.jpg\" alt=\"Dave kauft in Ensenada ein\" class=\"wp-image-11070\" srcset=\"\" sizes=\"(max-width: 1024px) 100vw, 1024px\" data-srcset=\"\" \/><figcaption>Verf\u00fcgbarkeit ist eine Bedrohung f\u00fcr unser Budget<\/figcaption><\/figure>\n\n\n\n<h3 class=\"has-text-align-center wp-block-heading\" id=\"h-4-will-you-also-work-en-route\">4. Werdet ihr unterwegs auch arbeiten?<\/h3>\n\n\n\n<p>Erst mal fokussieren wir uns auf den Umbau unseres Schiffes und das Erlernen einer guten Seemannschaft. Danach werden wir sicher in irgendeiner Form Geld verdienen. Denn die Rechnung ist ziemlich simpel: Wenn wir beide je 1'000 CHF pro Monat verdienen, k\u00f6nnen wir theoretisch ewig unterwegs sein. Ideen haben wir schon einige.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/milagros.ch\/wp-content\/uploads\/2021\/01\/sunset-1024x768.jpg\" alt=\"Sonnenuntergang auf dem Weg nach Puerto Pe\u00f1asco\" class=\"wp-image-11069\" srcset=\"\" sizes=\"(max-width: 1024px) 100vw, 1024px\" data-srcset=\"\" \/><figcaption>Wir m\u00f6chten vermutlich zuerst einige arbeitsfreie Sonnenunterg\u00e4nge geniessen\u2026<\/figcaption><\/figure>\n\n\n\n<h3 class=\"has-text-align-center wp-block-heading\" id=\"h-5-which-route-do-you-have-in-mind\">5. Welche Route habt ihr denn im Kopf?<\/h3>\n\n\n\n<p>Ja, mal schauen, wie weit wir kommen. Erst mal renovieren wir unser Schiff in Mexiko im Golf von Kalifornien. Dann segeln wir vielleicht in Richtung S\u00fcden bis etwa Ecuador, danach \u00fcber den Pazifik in die S\u00fcdsee. Von dort aus k\u00f6nnten wir via Indonesien, Japan, Madagaskar nach S\u00fcdafrika und dann die Westk\u00fcste von Afrika hinauf. Dann schauen wir weiter, ob wir den Atlantik \u00fcberqueren oder mit dem Schiff den Rhein hinauf nach Basel motoren. Oder vielleicht segeln wir nur bis Neuseeland und lassen uns dort nieder. Es gibt so viele M\u00f6glichkeiten, daher lassen wir alles auf uns zukommen.<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-2 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/milagros.ch\/wp-content\/uploads\/2021\/01\/attaching-the-headsail-768x1024.jpg\" alt=\"Montieren eines Soft Shackles um das Vorsegel zu hissen\" data-id=\"11075\" data-full-url=\"https:\/\/milagros.ch\/wp-content\/uploads\/2021\/01\/attaching-the-headsail.jpg\" data-link=\"https:\/\/milagros.ch\/10-faq\/attaching-the-headsail\/\" class=\"wp-image-11075\" srcset=\"\" sizes=\"(max-width: 768px) 100vw, 768px\" data-srcset=\"\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/milagros.ch\/wp-content\/uploads\/2021\/01\/routing-768x1024.jpg\" alt=\"M\u00f6gliche Ziele aussuchen\" data-id=\"11073\" data-full-url=\"https:\/\/milagros.ch\/wp-content\/uploads\/2021\/01\/routing.jpg\" data-link=\"https:\/\/milagros.ch\/10-faq\/routing\/\" class=\"wp-image-11073\" srcset=\"\" sizes=\"(max-width: 768px) 100vw, 768px\" data-srcset=\"\" \/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<h3 class=\"has-text-align-center wp-block-heading\" id=\"h-6-are-you-experienced-sailors\">6. Ja, seid ihr denn erfahrene Segler?<\/h3>\n\n\n\n<p>Dieser Frage m\u00fcssen wir jeweils etwas ausweichen und das Gegen\u00fcber beschwichtigen. Denn wir haben zwar beide mittlerweile den Binnenschein auf den Thunersee gemacht und die Theoriepr\u00fcfung f\u00fcr den Hochseeschein bestanden, sind jedoch abgesehen davon nicht sehr erfahren. Unser Joker ist unser \u00abprivater Segellehrer\u00bb, der uns vor Ort alles Notwendige beibringen kann.<\/p>\n\n\n\n<h3 class=\"has-text-align-center wp-block-heading\" id=\"h-7-isn-t-that-dangerous\">7. Ist das nicht gef\u00e4hrlich?<\/h3>\n\n\n\n<p>Hmm ja gut, ein gewisses Risiko gehen wir schon ein, aber wir k\u00f6nnen auch hier von einem Bus \u00fcberfahren werden. Auf die Folgefrage \u00abAber was ist, wenn ihr in einen Sturm kommt?\u00bb antworten wir meistens, dass entgegen der Annahme, dass man als Segler die ganze Zeit auf dem Meer ohne Land in Sicht verbringt, es eigentlich so ist, dass man ca. 80% der Zeit irgendwo (hoffentlich in einer sch\u00f6nen Bucht) vor Anker verbringt. Und dass ein Segler durchschnittlich etwa einen Tag pro Jahr in einem Sturm verbringt. Und ausserdem gibt es spezielle Sturmtaktikten, die wir nat\u00fcrlich zuerst auch erlernen m\u00fcssen.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/milagros.ch\/wp-content\/uploads\/2021\/01\/fish-cleaning-bottom-of-milagros-1024x768.jpg\" alt=\"Fische reinigen das Unterwasserschiff von Milagros\" class=\"wp-image-11076\" srcset=\"\" sizes=\"(max-width: 1024px) 100vw, 1024px\" data-srcset=\"\" \/><figcaption>Die Reinigungsmannschaft am Diesel-Dock<\/figcaption><\/figure>\n\n\n\n<h3 class=\"has-text-align-center wp-block-heading\" id=\"h-8-how-can-you-even-know-whether-you-will-like-it\">8. Aber wie k\u00f6nnt ihr \u00fcberhaupt wissen, ob es euch gefallen wird?<\/h3>\n\n\n\n<p>Das wissen wir nicht wirklich, denn wir haben noch nie \u00fcber eine l\u00e4ngere Zeit fix auf einem Segelschiff gelebt, aber wir hoffen es! Und wenn uns das Seglerleben nicht zusagt, sind wir schnell wieder zuhause oder reisen auf andere Art und Weise durch die Welt.<\/p>\n\n\n\n<h3 class=\"has-text-align-center wp-block-heading\" id=\"h-9-why-do-you-decide-to-leave-the-life-you-have-built-behind\">9. Wieso entscheidet man sich daf\u00fcr, das ganze Leben, das man sich aufgebaut hat, hinter sich zu lassen und alle Zelte abzubrechen?<\/h3>\n\n\n\n<p>Diese Frage stellen wir uns ab und zu noch selber. Die Antwort ist meistens: \"Weil wir es k\u00f6nnen\".<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-2 is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/milagros.ch\/wp-content\/uploads\/2021\/01\/pati-drinking-coffee-768x1024.jpg\" alt=\"Pati geniesst das Kaffeeritual auf Max&#039; Boot &#039;Galena &#039;\" data-id=\"11077\" data-full-url=\"https:\/\/milagros.ch\/wp-content\/uploads\/2021\/01\/pati-drinking-coffee.jpg\" data-link=\"https:\/\/milagros.ch\/10-faq\/pati-drinking-coffee\/\" class=\"wp-image-11077\" srcset=\"\" sizes=\"(max-width: 768px) 100vw, 768px\" data-srcset=\"\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/milagros.ch\/wp-content\/uploads\/2021\/01\/pati-eating-tacos-768x1024.jpg\" alt=\"Gl\u00fcckliche Pati am Tacos essen\" data-id=\"11078\" data-full-url=\"https:\/\/milagros.ch\/wp-content\/uploads\/2021\/01\/pati-eating-tacos.jpg\" data-link=\"https:\/\/milagros.ch\/10-faq\/pati-eating-tacos\/\" class=\"wp-image-11078\" srcset=\"\" sizes=\"(max-width: 768px) 100vw, 768px\" data-srcset=\"\" \/><\/figure><\/li><\/ul><figcaption class=\"blocks-gallery-caption\">Gutes Essen \u2013 because I can \ud83d\ude09<\/figcaption><\/figure>\n\n\n\n<h3 class=\"has-text-align-center wp-block-heading\" id=\"h-10-i-admire-your-courage-but-i-couldn-t-do-it\">10. Ich bewundere euren Mut, aber ich k\u00f6nnte das nicht.<\/h3>\n\n\n\n<p>Dies ist zwar keine Frage, jedoch eine in diesem Zusammenhang h\u00e4ufig gemachte Feststellung. Da ich oft nicht genau weiss, was ich darauf antworten soll, zitiere gerne Pippi Langstrumpf: \"Das habe ich noch nie vorher versucht, also bin ich v\u00f6llig sicher, dass ich es schaffe!\" oder etwas in die Richtung \"Ja, das Sicherheitsbed\u00fcrfnis ist von Mensch zu Mensch unterschiedlich\".<\/p>\n\n\n\n<h2 class=\"has-text-align-center wp-block-heading\" id=\"h-it-is-how-it-is\">Es ist wie es ist<\/h2>\n\n\n\n<p>Wir freuen uns jedenfalls darauf, alle M\u00f6glichkeiten offen zu haben und den Luxus zu haben, die Dinge einfach auf uns zukommen zulassen.<\/p>\n\n\n\n<p>Haben wir Fragen vergessen? Fragt uns in den Kommentaren, wir freuen uns auf eure Inputs!<\/p>\n\n\n\n<p>Hat dir dieser Blog-Beitrag gefallen? Du kannst auf\u00a0<a href=\"https:\/\/www.patreon.com\/milagros_sailing\" target=\"_blank\" rel=\"noreferrer noopener\">Patreon<\/a>\u00a0monatliche*r Unterst\u00fctzer*in werden oder uns ganz ohne Anmeldung ein Bier spendieren, wenn du auf den Button hier unter dem Text klickst. Vielen Dank!<\/p>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link\" href=\"https:\/\/www.buymeacoffee.com\/milagrossailing\" target=\"_blank\" rel=\"noreferrer noopener\">\ud83c\udf7a  Stosse mit uns an!<\/a><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Wenn wir von unserem Vorhaben erz\u00e4hlen, gibt es Fragen, die es immer und immer wieder zu beantworten gilt. Wir haben die 10 h\u00e4ufigsten Fragen und Antworten zusammengestellt.<\/p>","protected":false},"author":3,"featured_media":11066,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"cybocfi_hide_featured_image":"yes","footnotes":""},"categories":[1,17],"tags":[78],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.0 (Yoast SEO v23.5) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>10 Questions about our Adventure &#8226; Milagros &#8226; Sailing Blog 2021<\/title>\n<meta name=\"description\" content=\"When we talk about our project, there are questions that we answer over and over again. We have answered the 10 most frequently asked questions.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/milagros.ch\/de\/10-faq\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"10 Questions about our Adventure\" \/>\n<meta property=\"og:description\" content=\"When we talk about our sailing project, there are questions that we answer over and over again. We have put together the 10 most frequently asked questions.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/milagros.ch\/de\/10-faq\/\" \/>\n<meta property=\"og:site_name\" content=\"Milagros\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/milagros.sailing\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-07T06:30:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-04T09:49:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/milagros.ch\/wp-content\/uploads\/2021\/01\/title-10-faq.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1050\" \/>\n\t<meta property=\"og:image:height\" content=\"788\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Patricia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschrieben von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Patricia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/milagros.ch\/de\/10-faq\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/milagros.ch\/de\/10-faq\/\"},\"author\":{\"name\":\"Patricia\",\"@id\":\"https:\/\/milagros.ch\/#\/schema\/person\/bf6747fcb66e878e86c2169f4bf869af\"},\"headline\":\"10 Questions about our Adventure\",\"datePublished\":\"2021-01-07T06:30:47+00:00\",\"dateModified\":\"2021-08-04T09:49:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/milagros.ch\/de\/10-faq\/\"},\"wordCount\":883,\"commentCount\":11,\"publisher\":{\"@id\":\"https:\/\/milagros.ch\/#organization\"},\"image\":{\"@id\":\"https:\/\/milagros.ch\/de\/10-faq\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/milagros.ch\/wp-content\/uploads\/2021\/01\/title-10-faq.jpg\",\"keywords\":[\"Thoughts\"],\"articleSection\":[\"General\",\"Humble Beginnings\"],\"inLanguage\":\"de-CH\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/milagros.ch\/de\/10-faq\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/milagros.ch\/de\/10-faq\/\",\"url\":\"https:\/\/milagros.ch\/de\/10-faq\/\",\"name\":\"10 Questions about our Adventure &#8226; Milagros &#8226; Sailing Blog 2021\",\"isPartOf\":{\"@id\":\"https:\/\/milagros.ch\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/milagros.ch\/de\/10-faq\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/milagros.ch\/de\/10-faq\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/milagros.ch\/wp-content\/uploads\/2021\/01\/title-10-faq.jpg\",\"datePublished\":\"2021-01-07T06:30:47+00:00\",\"dateModified\":\"2021-08-04T09:49:18+00:00\",\"description\":\"When we talk about our project, there are questions that we answer over and over again. We have answered the 10 most frequently asked questions.\",\"breadcrumb\":{\"@id\":\"https:\/\/milagros.ch\/de\/10-faq\/#breadcrumb\"},\"inLanguage\":\"de-CH\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/milagros.ch\/de\/10-faq\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/milagros.ch\/de\/10-faq\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/milagros.ch\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"10 Questions about our Adventure\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/milagros.ch\/#website\",\"url\":\"https:\/\/milagros.ch\/\",\"name\":\"Milagros\",\"description\":\"Nice to meet you!\",\"publisher\":{\"@id\":\"https:\/\/milagros.ch\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/milagros.ch\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-CH\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/milagros.ch\/#organization\",\"name\":\"Milagros Sailing\",\"url\":\"https:\/\/milagros.ch\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-CH\",\"@id\":\"https:\/\/milagros.ch\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/milagros.ch\/wp-content\/uploads\/2021\/02\/Milagros_black.jpg\",\"contentUrl\":\"https:\/\/milagros.ch\/wp-content\/uploads\/2021\/02\/Milagros_black.jpg\",\"width\":512,\"height\":512,\"caption\":\"Milagros Sailing\"},\"image\":{\"@id\":\"https:\/\/milagros.ch\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/milagros.sailing\",\"https:\/\/www.instagram.com\/milagros_sailing\/\",\"https:\/\/www.linkedin.com\/company\/milagros-sailing\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/milagros.ch\/#\/schema\/person\/bf6747fcb66e878e86c2169f4bf869af\",\"name\":\"Patricia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-CH\",\"@id\":\"https:\/\/milagros.ch\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8642c08f46e95a6c774a41afa7f1b2c1?s=96&d=retro&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8642c08f46e95a6c774a41afa7f1b2c1?s=96&d=retro&r=g\",\"caption\":\"Patricia\"},\"url\":\"https:\/\/milagros.ch\/de\/author\/patriciabueeler\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"10 Questions about our Adventure &#8226; Milagros &#8226; Sailing Blog 2021","description":"Wenn wir von unserem Vorhaben erz\u00e4hlen, gibt es Fragen, die es immer und immer wieder zu beantworten gilt. Wir haben die 10 h\u00e4ufigsten Fragen beantwortet.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/milagros.ch\/de\/10-faq\/","og_locale":"de_DE","og_type":"article","og_title":"10 Questions about our Adventure","og_description":"When we talk about our sailing project, there are questions that we answer over and over again. We have put together the 10 most frequently asked questions.","og_url":"https:\/\/milagros.ch\/de\/10-faq\/","og_site_name":"Milagros","article_publisher":"https:\/\/www.facebook.com\/milagros.sailing","article_published_time":"2021-01-07T06:30:47+00:00","article_modified_time":"2021-08-04T09:49:18+00:00","og_image":[{"width":1050,"height":788,"url":"https:\/\/milagros.ch\/wp-content\/uploads\/2021\/01\/title-10-faq.jpg","type":"image\/jpeg"}],"author":"Patricia","twitter_card":"summary_large_image","twitter_misc":{"Geschrieben von":"Patricia","Gesch\u00e4tzte Lesezeit":"6 Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/milagros.ch\/de\/10-faq\/#article","isPartOf":{"@id":"https:\/\/milagros.ch\/de\/10-faq\/"},"author":{"name":"Patricia","@id":"https:\/\/milagros.ch\/#\/schema\/person\/bf6747fcb66e878e86c2169f4bf869af"},"headline":"10 Questions about our Adventure","datePublished":"2021-01-07T06:30:47+00:00","dateModified":"2021-08-04T09:49:18+00:00","mainEntityOfPage":{"@id":"https:\/\/milagros.ch\/de\/10-faq\/"},"wordCount":883,"commentCount":11,"publisher":{"@id":"https:\/\/milagros.ch\/#organization"},"image":{"@id":"https:\/\/milagros.ch\/de\/10-faq\/#primaryimage"},"thumbnailUrl":"https:\/\/milagros.ch\/wp-content\/uploads\/2021\/01\/title-10-faq.jpg","keywords":["Thoughts"],"articleSection":["General","Humble Beginnings"],"inLanguage":"de-CH","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/milagros.ch\/de\/10-faq\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/milagros.ch\/de\/10-faq\/","url":"https:\/\/milagros.ch\/de\/10-faq\/","name":"10 Questions about our Adventure &#8226; Milagros &#8226; Sailing Blog 2021","isPartOf":{"@id":"https:\/\/milagros.ch\/#website"},"primaryImageOfPage":{"@id":"https:\/\/milagros.ch\/de\/10-faq\/#primaryimage"},"image":{"@id":"https:\/\/milagros.ch\/de\/10-faq\/#primaryimage"},"thumbnailUrl":"https:\/\/milagros.ch\/wp-content\/uploads\/2021\/01\/title-10-faq.jpg","datePublished":"2021-01-07T06:30:47+00:00","dateModified":"2021-08-04T09:49:18+00:00","description":"Wenn wir von unserem Vorhaben erz\u00e4hlen, gibt es Fragen, die es immer und immer wieder zu beantworten gilt. Wir haben die 10 h\u00e4ufigsten Fragen beantwortet.","breadcrumb":{"@id":"https:\/\/milagros.ch\/de\/10-faq\/#breadcrumb"},"inLanguage":"de-CH","potentialAction":[{"@type":"ReadAction","target":["https:\/\/milagros.ch\/de\/10-faq\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/milagros.ch\/de\/10-faq\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/milagros.ch\/"},{"@type":"ListItem","position":2,"name":"10 Questions about our Adventure"}]},{"@type":"WebSite","@id":"https:\/\/milagros.ch\/#website","url":"https:\/\/milagros.ch\/","name":"Milagros","description":"Sch\u00f6n dich kennen zu lernen!","publisher":{"@id":"https:\/\/milagros.ch\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/milagros.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-CH"},{"@type":"Organization","@id":"https:\/\/milagros.ch\/#organization","name":"Milagros Sailing","url":"https:\/\/milagros.ch\/","logo":{"@type":"ImageObject","inLanguage":"de-CH","@id":"https:\/\/milagros.ch\/#\/schema\/logo\/image\/","url":"https:\/\/milagros.ch\/wp-content\/uploads\/2021\/02\/Milagros_black.jpg","contentUrl":"https:\/\/milagros.ch\/wp-content\/uploads\/2021\/02\/Milagros_black.jpg","width":512,"height":512,"caption":"Milagros Sailing"},"image":{"@id":"https:\/\/milagros.ch\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/milagros.sailing","https:\/\/www.instagram.com\/milagros_sailing\/","https:\/\/www.linkedin.com\/company\/milagros-sailing"]},{"@type":"Person","@id":"https:\/\/milagros.ch\/#\/schema\/person\/bf6747fcb66e878e86c2169f4bf869af","name":"Patricia","image":{"@type":"ImageObject","inLanguage":"de-CH","@id":"https:\/\/milagros.ch\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/8642c08f46e95a6c774a41afa7f1b2c1?s=96&d=retro&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8642c08f46e95a6c774a41afa7f1b2c1?s=96&d=retro&r=g","caption":"Patricia"},"url":"https:\/\/milagros.ch\/de\/author\/patriciabueeler\/"}]}},"_links":{"self":[{"href":"https:\/\/milagros.ch\/de\/wp-json\/wp\/v2\/posts\/11061"}],"collection":[{"href":"https:\/\/milagros.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/milagros.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/milagros.ch\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/milagros.ch\/de\/wp-json\/wp\/v2\/comments?post=11061"}],"version-history":[{"count":13,"href":"https:\/\/milagros.ch\/de\/wp-json\/wp\/v2\/posts\/11061\/revisions"}],"predecessor-version":[{"id":12853,"href":"https:\/\/milagros.ch\/de\/wp-json\/wp\/v2\/posts\/11061\/revisions\/12853"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/milagros.ch\/de\/wp-json\/wp\/v2\/media\/11066"}],"wp:attachment":[{"href":"https:\/\/milagros.ch\/de\/wp-json\/wp\/v2\/media?parent=11061"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/milagros.ch\/de\/wp-json\/wp\/v2\/categories?post=11061"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/milagros.ch\/de\/wp-json\/wp\/v2\/tags?post=11061"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}